{"id":11860,"date":"2023-01-15T18:26:28","date_gmt":"2023-01-15T17:26:28","guid":{"rendered":"https:\/\/www.aletheia-scimed.ch\/?p=11860"},"modified":"2023-01-15T20:09:51","modified_gmt":"2023-01-15T19:09:51","slug":"ist-es-nicht-hoechste-zeit-alte-muster-der-diffamierung-und-spaltung-endlich-zu-durchbrechen","status":"publish","type":"post","link":"https:\/\/www.aletheia-scimed.ch\/de\/ist-es-nicht-hoechste-zeit-alte-muster-der-diffamierung-und-spaltung-endlich-zu-durchbrechen\/","title":{"rendered":"Ist es nicht h\u00f6chste Zeit, alte Muster der Diffamierung und Spaltung endlich zu durchbrechen?"},"content":{"rendered":"<p id=\"viewer-6svbb\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Am 24. November 2022 hat, organisiert durch die <a href=\"https:\/\/www.paulusakademie.ch\/\" target=\"_blank\" rel=\"noopener\">Paulus Akademie in Z\u00fcrich<\/a>, eine Podiumsdiskussion unter <a href=\"https:\/\/www.paulusakademie.ch\/rethinking-corona\/\" target=\"_blank\" rel=\"noopener\">Beleuchtung der Rolle der Pharmaindustrie w\u00e4hrend der \u00abPandemie\u00bb<\/a> stattgefunden. Geplant war, dass vier Teilnehmer mit unterschiedlichen Meinungen einen kritisch konstruktiven Dialog f\u00fchren sollten. Leider kam es anders.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Denn, neben dem Pharma-Vertreter, ist Fabian Molina, Z\u00fcrcher SP-Nationalrat, von seiner Teilnahme nur wenige Stunden vor Beginn der Podiumsdiskussion zur\u00fcckgetreten.<\/span><\/p>\n<p>Wir haben am 28. November 2022 dar\u00fcber <a href=\"https:\/\/www.aletheia-scimed.ch\/de\/podiumsgespraeche-rethinking-corona\/\" target=\"_blank\" rel=\"noopener\">berichtet<\/a>.<\/p>\n<p><strong>Am 13. Januar 2023 ist nun unter kath.ch (eine Dienstleistung des Katholischen Medienzentrums im Auftrag der r\u00f6misch-katholischen Kirche in der Schweiz) eine &#8220;Story der Woche&#8221; mit dem Titel <a href=\"https:\/\/www.kath.ch\/newsd\/warum-die-covid-diskussion-in-der-paulus-akademie-problematisch-war\/\" target=\"_blank\" rel=\"noopener\">&#8220;Warum die Covid-Diskussion in der Paulus-Akademie problematisch war&#8221;<\/a> erschienen.<\/strong><\/p>\n<p>ALETHEIA Vorstands-Mitglied, <a href=\"https:\/\/www.katischepis.ch\/\" target=\"_blank\" rel=\"noopener\">Kati Schepis<\/a>, nimmt nachfolgend oder auf ihrer <a href=\"https:\/\/www.katischepis.ch\/post\/ist-es-nicht-h%C3%B6chste-zeit-alte-muster-der-diffamierung-und-spaltung-endlich-zu-durchbrechen\" target=\"_blank\" rel=\"noopener\">Webseite<\/a> zu den im Beitrag von kath.ch erw\u00e4hnten Punkte, sowie zu den ehrverletzenden \u00c4usserungen gegen ihre eigene Person ausf\u00fchrlich Stellung:<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Sehr geehrter Herr Rauch<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Als Mitglied der katholischen Kirche war ich zutiefst ersch\u00fcttert, als ich den am 13.1.2023 auf kath.ch publizierten Artikel \u00abWarum die Covid-Diskussion in der Paulus-Akademie problematisch war\u00bb [1] gelesen habe. In diesem Artikel werden ich (und auch Prof. Vernazza) in einer respektlosen und einmal mehr unfundierten und traurigen Weise diffamiert. Es stimmt mich \u00e4usserst nachdenklich, Herr Rauch, dass Sie als Redaktionsleiter einer katholischen Plattform der Ver\u00f6ffentlichung eines Artikels zustimmen konnten, der, einmal mehr, \u00abHinterfragende\u00bb als \u00abextremistische Leugner\u00bb hinstellt und so, nach altbekanntem Muster, erneut eine tiefe Kerbe in die Gesellschaft treibt und jeglichen Diskurs \u00abradikal\u00bb unterbindet. Ihr Artikel widerspricht f\u00fcr mich s\u00e4mtlichen Werten, welche die Kirche bis anhin vertrat.<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Viele Gl\u00e4ubige und ich haben nie verstanden, weshalb die Katholische Kirche an Ostern 2020 ihre T\u00fcren f\u00fcr Messen g\u00e4nzlich schloss und Kirchen \u00abvergeistern\u00bb liess, wo sie doch ein Ort sind, an dem Menschen in einer Krisensituation normalerweise Trost und Hoffnung finden. Da jedem, der von Anfang an kritisch recherchierte, schon im Sommer 2021 l\u00e4ngst klar war, dass die \u00abImpfung\u00bb vor keiner Ansteckung sch\u00fctzt, schien es geradezu grotesk, dass die Kirchen Menschen, die ihre Gesundheit nicht mit einem Zertifikat bezeugen konnten, an Weihnachten 2021 im Namen der \u00abSolidarit\u00e4t\u00bb vom Gottesdienst ausschlossen. Alle Menschen, welche die \u00e4usserst d\u00fcnne Datenlage zu den \u00abCOVID-Impfungen\u00bb und die sehr wohl bekannten Risiken kannten, staunten nicht schlecht, als der Vatikan im Sommer 2022 gar eine \u00abImpfm\u00fcnze\u00bb herausbrachte. [2]<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Als Pharmazeutin, die \u00fcber zw\u00f6lf Jahre in der Pharmaindustrie gearbeitet hat und dort tagt\u00e4glich Studien analysieren musste, befremdet es mich, wenn meine Expertise von zwei Journalisten diskreditiert wird, die von der Materie, wie sich im Artikel offenbart, wenig Ahnung haben. Meine Einsch\u00e4tzung zur \u00abImpfung\u00bb deckt sich mit der Meinung von weltweit tausenden von \u00c4rzten und Wissenschaftlern [3], welche sich durch Diffamierungsversuche nicht einsch\u00fcchtern lassen und welche es als ihre Pflicht ansehen, die Bev\u00f6lkerung auf die Risiken der \u00abImpfung\u00bb aufmerksam zu machen. \u00dcbrigens hiess es fr\u00fcher nicht \u00abVerschw\u00f6rung\u00bb, sondern Zivilcourage, wenn man das Wort erhob, um die Gesellschaft und ihre Schw\u00e4chsten zu sch\u00fctzen.<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Da die Anschuldigungen auf meine Person in Ihrem Artikel schwer wiegen, verletzend und rufsch\u00e4digend sind, m\u00f6chte ich in den nachfolgenden Abschnitten im Sinne eines \u00abPoint-to-point-Reply\u00bb gerne Stellung zu den wichtigsten Punkten nehmen:<\/span><\/p>\n<p><em><strong><span class=\"_2PHJq public-DraftStyleDefault-ltr\">1. \u00abSie leugnet die Gef\u00e4hrlichkeit von COVID-19 und behauptet, es h\u00e4tte nie eine \u00dcberlastung der Spit\u00e4ler gegeben\u00bb:<\/span><\/strong><\/em><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Anthony Fauci selbst schlussfolgerte im M\u00e4rz 2020, dass die Zahlen darauf hindeuteten, dass die klinischen Folgen von COVID-19 letztlich mit denjenigen einer schweren saisonalen Grippe vergleichbar seien: \u00ab<em>This suggests that the overall clinical consequences of COVID-19 may ultimately be more akin to those of a severe seasonal influenza (\u2026) or a pandemic influenza.<\/em>\u00bb [4]<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Gem\u00e4ss WHO liegt die Letalit\u00e4t bei der saisonalen Grippe (Influenza, \u00abflu\u00bb) normalerweise unter 0.1%, [5] diejenige von COVID f\u00fcr unter 70-J\u00e4hrige bei &lt;0.05. [6]<\/span><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Die Amerikanische CDC ging schon in im M\u00e4rz 2021 in Szenarien von Werten aus, die nach einer vern\u00fcnftigen Nutzen-Risiko-Analyse h\u00f6chstens gerechtfertigt h\u00e4tten, \u00e4ltere Menschen mit einer g\u00e4nzlich neuartigen gentechnischen Methode zu \u00abimpfen\u00bb:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11905 size-full\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021.jpg\" alt=\"\" width=\"920\" height=\"361\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021.jpg 920w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021-300x118.jpg 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021-768x301.jpg 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/p>\n<p><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Werden die obigen Zahlen auf eine Letalit\u00e4tsrate in % umgerechnet, wird ersichtlich, dass auch die CDC vorab die \u00e4ltere Bev\u00f6lkerung durch SARS-CoV-2 bedroht sah:<\/span><\/p>\n<div id=\"viewer-9s3ec\" class=\"_2vd5k b6lcWf\">\n<div class=\"_3CWa- sxFoib sxFoib _3mymk\">\n<div class=\"_2kEVY\" tabindex=\"0\" role=\"button\" data-hook=\"imageViewer\">\n<div id=\"new-image15\" class=\"_3WJnn _2i-Gt _2Ybje\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11908 size-full\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021_2.jpg\" alt=\"\" width=\"925\" height=\"173\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021_2.jpg 925w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021_2-300x56.jpg 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/CDC_03-2021_2-768x144.jpg 768w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Zur (wahren) Auslastung der Spit\u00e4ler verweise ich auf <a href=\"https:\/\/www.dieostschweiz.ch\/artikel\/froehliche-zahlenknobelei-oder-reise-nach-jerusalem-a3g33v7\" target=\"_blank\" rel=\"noopener\">diesen Artikel<\/a>, welcher zahlreiche Screenshots der BAG-Zahlen enth\u00e4lt.<\/span><\/p>\n<p id=\"viewer-2jpsm\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Am 17.12.2020, als Spitaldirektoren und \u00c4rzte in den Medien einen Lockdown \u00abherbeibeteten\u00bb, waren die Spit\u00e4ler zu 75.8% ausgelastet. Per Stand 10.1.2023 liegt die Auslastung bei 82.6%. [7]<\/span><\/p>\n<p id=\"viewer-25e7t\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><strong><span class=\"_2PHJq public-DraftStyleDefault-ltr\"><em>2. \u00abSie sagt, das prim\u00e4re Studienziel der Zulassungsstudien sei die Vermeidung von Bagatellsymptomen (plus PCR-Positivit\u00e4t) gewesen. Die Vermeidung von schweren Erkrankungen sei sekund\u00e4res Studienziel gewesen. Dabei ist das nicht richtig: In den Zulassungsstudien ging es vor allem um den Vergleich von zuvor definierten Erkrankungsereignissen in der Impf- und Kontrollgruppe.\u00bb<\/em> <\/span><\/strong><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Es scheint, dass die Autoren nie ein Studienprotokoll durchgelesen haben, sonst w\u00fcssten sie, dass meine Angaben stimmen. Die Beschreibung einer COVID-Erkrankung (=prim\u00e4rer Wirksamkeitsendpunkt) findet sich z.B. beim Pfizer-\u00abImpfstoff\u00bb im Studienprotokoll [8] auf S. 56. Aufgelistet findet man hier exakt die von mir beschriebenen \u00abBagatellereignisse\u00bb und als separaten Punkt die schweren COVID-Erkrankungen.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">In den 2-Monatsresultaten, welche Basis f\u00fcr die Erteilung der befristeten Zulassung vom Pfizer-\u00abImpfstoff\u00bb im Dezember 2020 waren, traten in der \u00abImpfstoffgruppe\u00bb nur bei 8 von 21\u2019720 (=0.04%) und in der Placebogruppe nur bei 162 von 21\u2019728 (=0.74%) eine \u00abbest\u00e4tigte COVID-19- Erkrankung\u00bb auf. [9] Separat wird \u00fcber 4 F\u00e4lle von schweren COVID-Erkrankungen berichtet. Die Fallzahlen lagen somit im Bereich des statistischen Zufalls. In der Fachinformation mit Stand vom Dezember 2020 wurde dies folgendermassen festgehalten:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11911 size-full\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Covid-19_schwererVerlauf_12-2020..jpg\" alt=\"\" width=\"915\" height=\"189\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Covid-19_schwererVerlauf_12-2020..jpg 915w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Covid-19_schwererVerlauf_12-2020.-300x62.jpg 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Covid-19_schwererVerlauf_12-2020.-768x159.jpg 768w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/p>\n<div>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Finden Sie, werter Herr Rauch, es nicht auch etwas erstaunlich, dass in der Studie trotz \u00abgrassierender Pandemie\u00bb nur so wenig Studienteilnehmer erkrankt sind und dass basierend auf 4 bei rund 40&#8217;000 Probanden proklamiert wurde, dass die \u00abImpfung\u00bb schwere Verl\u00e4ufe verhindert? Diese F\u00e4lle stiegen im Verlauf nur wenig an. Schon im Dezember 2020 wurde in der Zulassungsstudie \u00abaus ethischen Gr\u00fcnden\u00bb die Kontrollgruppe aufgehoben, obwohl bis dahin kein relevanter Nutzen belegt worden ist. Es wird somit nie mehr m\u00f6glich sein, basierend auf den Zulassungsstudien eine solide Aussage zu Wirksamkeit und Sicherheit zu machen.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><strong><em><span class=\"_2PHJq public-DraftStyleDefault-ltr\">3. \u00abKati Schepis hat alle nicht kontrolliert und randomisiert durchgef\u00fchrten Studien grunds\u00e4tzlich v\u00f6llig abgewertet, geht nicht auf diese ein und es wird nicht klar, ob sie die aktuelle umfangreiche Literatur kennt. Sie pickt Fakten heraus und \u00fcbt Kritik an den Zulassungsstudien, wohingegen sie nichts zu den Postmarketing-Studien sagt (zum Beispiel England, Israel, USA), welche die Wirksamkeit der Impfung an grossen Kollektiven sehr gut quantitativ belegen. Sie kritisiert diese Studien pauschal als minderwertig, was nicht haltbar ist.\u00bb<\/span><\/em><\/strong><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Es scheint, die Autoren kennen sich nicht mit der Systematik von Studien aus. Sie wissen nicht, dass es v\u00f6llig un\u00fcblich ist, in der Medizin Leitlinien auf nicht kontrollierte randomisierte Studien (RCT) zu st\u00fctzen, da diese per se sehr fehleranf\u00e4llig und wenig aussagekr\u00e4ftig sind. [10]<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11902 size-full\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/SystematikvonStudien.jpg\" alt=\"\" width=\"832\" height=\"494\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/SystematikvonStudien.jpg 832w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/SystematikvonStudien-300x178.jpg 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/SystematikvonStudien-768x456.jpg 768w\" sizes=\"auto, (max-width: 832px) 100vw, 832px\" \/><\/p>\n<p id=\"viewer-fb4a0\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Bei Postmarketingstudien (=Real World Evidence-Studien) handelt es sich \u00fcblicherweise um Datenbankanalysen, Beobachtungs- oder Modellierungsstudien, welche in der unteren H\u00e4lfte der \u00abEvidenzpyramide\u00bb anzusiedeln sind.<\/span><\/p>\n<p id=\"viewer-89svb\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Die \u00f6ffentlichen Medien verweisen zwecks Belegs f\u00fcr die Wirksamkeit von \u00ab\u00fcber 90%\u00bb gerne auf eine \u00abisraelische Studie\u00bb. Bei den drei bekannten Studien aus Israel, welche einen (vermeintlich) hohen Nutzen zeigen, handelt es sich um eine \u00abBeobachtungs-\u00bb [11], eine \u00abModellierungsstudie\u00bb [12] und um eine Datenbankanalyse [13]. Bei Datenbankanalysen, welche die Raten von COVID-F\u00e4llen, COVID-Hospitalisationen oder gar Todesf\u00e4llen in diesem Zusammenhang analysieren, ist die Problematik, dass \u00abGeimpfte\u00bb und \u00abUngeimpfte\u00bb in den analysierten Zeitperioden ungleich behandelt wurden: \u00abGeimpfte\u00bb wurden in Israel bei einem Spitaleintritt nicht getestet, weshalb es nur schon aus diesem Grund logisch ist, dass bei den \u00abUngeimpften\u00bb mehr COVID-Hospitalisationen generiert wurden.[14] Angaben in diesen Datenbanken sind deshalb nicht aussagekr\u00e4ftig und valide, um Wirksamkeitsaussagen f\u00fcr die \u00abImpfung\u00bb daraus abzuleiten. Oftmals werden in Datenbankanalysen auch COVID-Zahlen aus der Zeitperiode hinzugez\u00e4hlt, als die \u00abImpfung\u00bb noch nicht zugelassen war und somit selbstverst\u00e4ndlich nur \u00abUngeimpfte\u00bb an COVID erkranken konnten, was die Fallzahlen f\u00fcr \u00abUngeimpfte\u00bb hochtreibt und insgesamt f\u00e4lschlicherweise eine Wirksamkeit der \u00abImpfung\u00bb impliziert.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Prof. Jacob Giris, Leiter der COVID-Abteilung des Ichilov-Krankenhauses in Tel Aviv, gab in einem Interview Anfangs Februar 2022 bekannt, dass 70-80% der schwer an COVID erkrankten hospitalisierten Patienten dreifach \u00abgeimpft\u00bb seien und dass die \u00abImpfung\u00bb zur Verhinderung von schweren Verl\u00e4ufen keine Bedeutung habe [15]. Der europ\u00e4ische Mortalit\u00e4ts-Monitor EuroMomo wies f\u00fcr Israel f\u00fcr das erste Quartal 2022, als die Mehrheit \u00abgeimpft\u00bb war, die h\u00f6chste \u00dcbersterblichkeit seit Beginn der \u00abCorona-Krise\u00bb aus. Anstiege der \u00dcbersterblichkeitskurven korrelierten zeitlich mit den \u00abImpfkampagnen\u00bb: [16]<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11899 size-full\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Grafik_TelAviv_03-2022.jpg\" alt=\"\" width=\"925\" height=\"476\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Grafik_TelAviv_03-2022.jpg 925w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Grafik_TelAviv_03-2022-300x154.jpg 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2023\/01\/Grafik_TelAviv_03-2022-768x395.jpg 768w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/><\/p>\n<\/div>\n<p id=\"viewer-61ce\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Der Artikel, welcher obige Graphik enth\u00e4lt, beschreibt ausserdem ausf\u00fchrlich, dass eine Modellierungsstudie, welche propagierte, dass die COVID-\u00abImpfstoffe\u00bb 14 Millionen Todesf\u00e4lle verhinderten auf falschen Annahmen basiert und mit gravierenden Interessenskonflikten behaftet ist. Modellierungsstudien k\u00f6nnen, je nach W\u00fcnschen der Geldgeber, selbstverst\u00e4ndlich immer in die gew\u00fcnschte Richtung \u00abmodelliert\u00bb werden. Dies hat mit Wissenschaft nichts zu tun.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><em><strong><span class=\"_2PHJq public-DraftStyleDefault-ltr\">4. \u00abZum Abschluss liefert Kati Schepis ein Feuerwerk an angeblichen schwersten Nebenwirkungen: Spikeproteine verursachten Thrombosen, Krebserkrankungen und die Fehlgeburten n\u00e4hmen impfbedingt zu.\u00bb<\/span><\/strong><\/em><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Der Zusammenhang der COVID-\u00abImpfungen\u00bb mit zahlreichen schweren Nebenwirkungen (u.a. Thrombosen, Embolien und Schlaganf\u00e4llen) wurde mittlerweile in \u00fcber 1250 peer reviewten Artikeln belegt [17]. Zahlen der medizinischen epidemiologischen Datenbank des US-Milit\u00e4rs zeigen seit Start der COVID-19-\u00abImpfkampagne\u00bb im Vergleich zum F\u00fcnfjahresdurchschnitt eine Zunahme von Herzinfarkten um 270%, von Lungenembolien um 460%, von Nervenerkrankungen um 1000%, von Brustkrebs um 490%, von Fazialisparesen (Gesichtsl\u00e4hmungen) um 290%, vom Guillain-Barr\u00e9-Syndrom (ein schweres neurologisches Krankheitsbild mit L\u00e4hmungen, die meist beidseitig in den Beinen beginnen) um 550% und von Fehlgeburten um 280%. [18]<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Eine Auff\u00fchrung der von Beh\u00f6rden registrierten und von mir zitierten Nebenwirkungen finden Sie in zahlreichen Datenbanken [19]. Beim Interpretieren dieser Zahlen ist zu bedenken, dass Studien gezeigt haben, dass deutlich &lt;10% der Nebenwirkungen gemeldet werden. [20]<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><strong><em><span class=\"_2PHJq public-DraftStyleDefault-ltr\">5. \u00abSwissmedic habe die Zulassungskriterien gesenkt, weil sie von der Pharmaindustrie gesponsort werde.\u00bb<\/span><\/em><\/strong><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Es gilt die Unschuldsvermutung. Gerne m\u00f6chte ich Ihnen und Ihren Autoren nahelegen, die 300-seitige Strafanzeige [21], welche gegen Swissmedic eingereicht wurde und die dazu verlinkten Dokumente durchzulesen, um sich ein Bild zu machen, ob geltende Standards bei der Zulassung der COVID-Impfstoffe angewendet wurden oder nicht.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Werter Herr Rauch, ich bin ein \u00e4usserst friedlicher Mensch und befinde mich weit weg von extremistischem Gedankengut.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">W\u00e4re ich \u00abradikal\u00bb, w\u00fcrde ich eine sofortige \u00f6ffentliche Berichtigung verlangen, eine Publikation dieser \u00abReplik\u00bb auf kath.ch fordern und mit juristischen Massnahmen wegen \u00abEhrverletzung\u00bb drohen. <\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Als besorgte Naturwissenschaftlerin, der das Wohl der Bev\u00f6lkerung am Herzen liegt, biete ich Ihnen hiermit gerne einen gek\u00fcrzten Artikel mit den hier aufgelisteten wichtigsten wissenschaftlichen Punkten an, den Sie im Sinne einer fairen Gegendarstellung auf Ihrem Portal ver\u00f6ffentlichen k\u00f6nnen.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Gerne erwarte ich Ihre R\u00fcckmeldung.<\/span><\/p>\n<p class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">P.S. Ich glaube, <a href=\"https:\/\/www.kath.ch\/wp-content\/uploads\/sites\/2\/2020\/11\/201028-093-000039-bearb-bm-c-kna.jpg\" target=\"_blank\" rel=\"noopener\">Jesus h\u00e4tte beim Abendmahl niemals eine Maske getragen<\/a>, da er sich vorher mit den rund 400 Studien auseinandergesetzt h\u00e4tte, welche gezeigt haben, dass Masken und andere \u00abLockdown-Massnahmen\u00bb bei einer Pandemie keinen positiven Einfluss haben. [22<\/span><span class=\"_2PHJq public-DraftStyleDefault-ltr\">]<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 24. November 2022 hat, organisiert durch die Paulus Akademie in Z\u00fcrich, eine Podiumsdiskussion unter Beleuchtung der Rolle der Pharmaindustrie w\u00e4hrend der \u00abPandemie\u00bb stattgefunden. Geplant war, dass vier Teilnehmer mit unterschiedlichen Meinungen einen kritisch konstruktiven Dialog f\u00fchren sollten. Leider kam es anders. Denn, neben dem Pharma-Vertreter, ist Fabian Molina, Z\u00fcrcher SP-Nationalrat, von seiner Teilnahme nur [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,47,42,5],"class_list":["post-11860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corona","category-veranstaltungen","category-events","category-virus"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:22:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/11860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/comments?post=11860"}],"version-history":[{"count":34,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/11860\/revisions"}],"predecessor-version":[{"id":11921,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/11860\/revisions\/11921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media\/10680"}],"wp:attachment":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media?parent=11860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/categories?post=11860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}