{"id":22193,"date":"2025-02-20T14:43:30","date_gmt":"2025-02-20T13:43:30","guid":{"rendered":"https:\/\/www.aletheia-scimed.ch\/?p=22193"},"modified":"2025-02-20T14:46:08","modified_gmt":"2025-02-20T13:46:08","slug":"erklaervideo-ueber-die-who-und-ihre-plaene","status":"publish","type":"post","link":"https:\/\/www.aletheia-scimed.ch\/de\/erklaervideo-ueber-die-who-und-ihre-plaene\/","title":{"rendered":"Erkl\u00e4rvideo \u00fcber die WHO und ihre Pl\u00e4ne"},"content":{"rendered":"\n<p><strong>ALETHEIA unterst\u00fctzt die Bem\u00fchungen zur Aufkl\u00e4rung der Bev\u00f6lkerung \u00fcber die gr\u00f6sseren Zusammenh\u00e4nge \u00fcber die Pl\u00e4ne der WHO. <\/strong><\/p>\n\n\n\n<p>Wir von der EDU haben k\u00fcrzlich ein ausf\u00fchrliches Erkl\u00e4rvideo produziert, mit dem wir die Bev\u00f6lkerung \u00fcber die WHO und ihre Pl\u00e4ne informieren wollen.&nbsp;Daniel Frischknecht, Pr\u00e4sident der EDU Schweiz, erkl\u00e4rt in diesem neuen Video, was die WHO mit den neuen Vertr\u00e4gen vorhat und weshalb die Schweiz die WHO sofort verlassen muss. Ebenso teilt&nbsp;EDU-Nationalrat Andreas Gafner&nbsp;im Video mit, dass er nun&nbsp;definitiv in der M\u00e4rz-Session des Nationalrats einen parlamentarischen Vorstoss einreichen wird, um einen WHO-Austritt der Schweiz zu erwirken.<\/p>\n\n\n\n<p>Hier der Link zum Video:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Warum die Schweiz aus der Weltgesundheitsorganisation austreten muss\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xMHqk8eOzq4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Liebe LeserInnen; helfen Sie mit den Inhalt dieses Videos zu verbreiten, sodass eine aufgekl\u00e4rte Bev\u00f6lkerung Einsicht \u00fcber diese wichtige, uns alle betrefffende Thematik WHO, erh\u00e4lt. &nbsp;<\/p>\n\n\n\n<p>Wir danken Ihnen f\u00fcr Ihren wertvollen Einsatz f\u00fcr eine freie Schweiz!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALETHEIA unterst\u00fctzt die Bem\u00fchungen zur Aufkl\u00e4rung der Bev\u00f6lkerung \u00fcber die gr\u00f6sseren Zusammenh\u00e4nge \u00fcber die Pl\u00e4ne der WHO. Wir von der EDU haben k\u00fcrzlich ein ausf\u00fchrliches Erkl\u00e4rvideo produziert, mit dem wir die Bev\u00f6lkerung \u00fcber die WHO und ihre Pl\u00e4ne informieren wollen.&nbsp;Daniel Frischknecht, Pr\u00e4sident der EDU Schweiz, erkl\u00e4rt in diesem neuen Video, was die WHO mit den [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":22194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[119],"class_list":["post-22193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-who"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:06:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/22193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/comments?post=22193"}],"version-history":[{"count":4,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/22193\/revisions"}],"predecessor-version":[{"id":22200,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/22193\/revisions\/22200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media\/22194"}],"wp:attachment":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media?parent=22193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/categories?post=22193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}