{"id":928,"date":"2022-03-28T10:29:50","date_gmt":"2022-03-28T08:29:50","guid":{"rendered":"https:\/\/www.aletheia-scimed.ch\/?p=928"},"modified":"2022-06-22T23:26:43","modified_gmt":"2022-06-22T21:26:43","slug":"welche-risiken-bergen-die-covid-19-impfstoffe-im-vergleich-zu-herkoemmlichen-impfstoffen","status":"publish","type":"post","link":"https:\/\/www.aletheia-scimed.ch\/de\/welche-risiken-bergen-die-covid-19-impfstoffe-im-vergleich-zu-herkoemmlichen-impfstoffen\/","title":{"rendered":"Welche Risiken bergen die &#8220;Covid-19-Impfstoffe&#8221; im Vergleich zu herk\u00f6mmlichen Impfstoffen?"},"content":{"rendered":"<h2>Mehr Verdachtsmeldungen mit bleibenden Sch\u00e4den und Todesfolgen<\/h2>\n<p>Die Initiative Wissenschaft f\u00fcr Gesellschaft\u00a0<a href=\"https:\/\/wiges.org\/\" target=\"_blank\" rel=\"noopener\">WIGES<\/a>\u00a0zeigt in einer f\u00fcr jeden einfach verst\u00e4ndlichen Art auf, dass die Risiken der \u00abCOVID-19 Impfstoffe\u00bb um mindestens zweistellige Faktoren h\u00f6her sind als bisher angenommen und bekannt. Dabei haben Experten die Daten der offiziellen Meldesysteme f\u00fcr Impfnebenwirkungen in Deutschland, Europa, USA, sowie der WHO nach nun 15 Monaten der Anwendung der \u00abImpfstoffe\u00bb ausgewertet und mit den Nebenwirkungsmeldungen anderer weit verbreiteter und seit langem eingesetzten Impfstoffe verglichen.<\/p>\n<p>Die ausgewerteten Zahlen aus Deutschland (siehe Grafik) zeigen ein \u00e4usserst besorgniserregendes Bild. Verglichen mit den Grippeimpfstoffen weisen die \u00abCOVID-19-Impfstoffe\u00bb rund 170 mal mehr Verdachtsmeldungen mit bleibenden Sch\u00e4den und rund 40 mal mehr Verdachtsmeldungen mit Todesfolge aus.<\/p>\n<p>Auch ein Vergleich mit den Rohdaten aus dem US-Meldesystem \u00abVAERS\u00bb best\u00e4tigt dieses Bild strukturell und deutet im Vergleich zu Deutschland sogar auf ein sehr wahrscheinlich noch h\u00f6heres Risiko f\u00fcr Todesf\u00e4lle nach Verabreichung der \u00abCOVID-19 Impfstoffe\u00bb hin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-933 size-large\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-1024x429.png\" alt=\"\" width=\"1024\" height=\"429\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-1024x429.png 1024w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-300x126.png 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-768x322.png 768w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-450x188.png 450w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-900x377.png 900w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-940x394.png 940w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/Grafische_statistik_Impfnebenwirkungen-1880x787.png 1880w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><em>E<\/em><em>in Vergleich zwischen verschiedenen Impfstoffen f\u00fcr Deutschland zeigt ein \u00e4usserst schlechtes Risiko-Profil der \u00abCOVID-19 Impfstoffe\u00bb. Diese Zahlen basieren auf den offiziellen Statistiken des Paul-Ehrlich-Instituts (f\u00fcr die Anzahl der Nebenwirkungs-Verdachtsf\u00e4lle) sowie dem <a href=\"https:\/\/www.arzneimittel-atlas.de\/arzneimittel\/j07-impfstoffe\/verbrauch\/\" target=\"_blank\" rel=\"noopener\">Arzneimittel-Atlas<\/a>\u00a0(f\u00fcr die Anzahl der Grippe-Impfungen).<br \/>\n<a href=\"https:\/\/wiges.org\/impfnebenwirkungen\" target=\"_blank\" rel=\"noopener\">Grafik wiges Impfnebenwirkungen<\/a><\/em><\/p>\n<p>Vergleicht man diese Zahlen mit der Europ\u00e4ischen Datenbank f\u00fcr Medikamentennebenwirkungen \u00abEUDRA Vigilance\u00bb, so zeigen diese etwas weniger Verdachtsf\u00e4lle mit Todesfolge und auch etwas weniger Verdachtsf\u00e4lle f\u00fcr bleibende Sch\u00e4den, aber die Grundstruktur des Vergleiches von Verdachtsmeldungen erscheint auch hier aussergew\u00f6hnlich ung\u00fcnstig. Bei sehr konservativer Betrachtung werden auch hier 20 bis 30 mal mehr Nebenwirkungs-Verdachtsf\u00e4lle mit bleibenden Sch\u00e4den oder sogar Todesfolge durch die \u00abCOVID-19 Impfstoffe\u00bb registriert. Das h\u00e4ufig vorgebrachte Argument, die Nebenwirkungen f\u00fcr die \u00abCOVID-19 Impfstoffe\u00bb w\u00fcrden \u00fcberbewertet, da noch nie in so kurzer Zeit so viele Impfstoffe verabreicht wurden, wird in der vorliegenden Betrachtung widerlegt, weil die Zahlen auf jeweils eine Million verimpfte Dosen standardisiert wurden. Auch ist zu beachten, dass die Verdachtsmeldungen f\u00fcr die anderen Impfstoffe sogar auf einer kumulativ h\u00f6heren Gesamtzahl von verimpften Dosen basieren, als die der Covid-Impfstoffe.<\/p>\n<h2><strong>Indizien f\u00fcr eine massive Untererfassung von Nebenwirkungen<\/strong><\/h2>\n<p>Laut\u00a0<a href=\"https:\/\/digital.ahrq.gov\/sites\/default\/files\/docs\/publication\/r18hs017045-lazarus-final-report-2011.pdf#:~:text=Adverse%20events%20from%20drugs%20and,and%20Drug%20Administration%20(FDA)\" target=\"_blank\" rel=\"noopener\">Untersuchungen<\/a>\u00a0wurden schon immer deutlich unter 5% von Impfnebenwirkungen gemeldet. Die dauernde Wiederholung von Politik und Medien, die \u00abCOVID-19-Impfstoffe\u00bb seien \u00abeffektiv und sicher\u00bb hat wohl zus\u00e4tzlich dazu gef\u00fchrt, dass besonders in einem Land wie der Schweiz, in dem das Vertrauen in Institutionen und Beh\u00f6rden sehr hoch ist, sehr wenig Nebenwirkungen gemeldet werden. Vergleicht man die Schweizer Meldequote mit anderen L\u00e4ndern in Europa, so liegt unsere Meldequote im Vergleich zu Island 10 mal tiefer, im Vergleich zu Holland immerhin noch 7 mal tiefer. Auch im Vergleich zu Deutschland werden hierzulande nur halb so viel Nebenwirkungen gemeldet oder zumindest von Swissmedic offiziell bekannt gegeben. Wird davon ausgegangen, dass die weltweit verwendeten Impfstoffchargen vergleichbar sind und Nebenwirkungen seri\u00f6s gemeldet und von Zulassungsbeh\u00f6rden transparent offengelegt werden, w\u00e4re selbstverst\u00e4ndlich in allen L\u00e4ndern von \u00e4hnlichen Melderaten auszugehen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-936 size-large\" src=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-1024x733.png\" alt=\"\" width=\"1024\" height=\"733\" srcset=\"https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-1024x733.png 1024w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-300x215.png 300w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-768x550.png 768w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-320x230.png 320w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-700x500.png 700w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-450x322.png 450w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-900x644.png 900w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-940x673.png 940w, https:\/\/www.aletheia-scimed.ch\/wp-content\/uploads\/2022\/06\/dunkelziffer_impfnebenwirkungen-1880x1346.png 1880w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><em>Die Meldequote f\u00fcr die Schweiz ist auff\u00e4llig gering und deutet auf eine hohe Dunkelziffer hin.<br \/>\n<\/em><em> <a href=\"https:\/\/wiges.org\/impfnebenwirkungen\" target=\"_blank\" rel=\"noopener\">Grafik wiges Impfnebenwirkungen<\/a><\/em><\/p>\n<h2><strong>Das relative Risiko im Vergleich zu anderen Impfstoffen ist massiv h\u00f6her<\/strong><\/h2>\n<p>Die vom BAG gemeldeten Infektionen zum H\u00f6hepunkt der Omikron-Welle im Januar 2022 betrugen im t\u00e4glichen Durchschnitt 36\u2019000. Die COVID-19 Todesf\u00e4lle im 2 bis 4 Wochen-Zeitraum danach lag bei zirka 12. Daraus kann ein Sterberisiko nach Infektion von 0.033% berechnet werden, was rund 6 mal tiefer ist als bei einer Grippe. W\u00e4hrend das Risiko, nach einer Infektion mit SARS-CoV-2 daran zu sterben, also viel tiefer als bei der Grippe liegt, ist das Risiko an der \u00abCOVID-19-Impfung\u00bb zu sterben mindestens 20 mal h\u00f6her als beim Grippeimpfstoff.<\/p>\n<p>Somit d\u00fcrfte das Nutzen-Risiko Profil der \u00abCOVID-19 Impfstoffe\u00bb betreffend Todesf\u00e4lle um rund 100 mal schlechter sein als jenes der Grippeimpfstoffe. Es muss daher dringend die Frage beantwortet werden, weshalb Politiker, Beh\u00f6rdenvertreter und Experten bereits wieder von der Notwendigkeit eines Boosters sprechen. Wir weisen zudem darauf hin, dass sogar die europ\u00e4ische Medikamentenzulassungsbeh\u00f6rde EMA vor einer\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-01-11\/repeat-booster-shots-risk-overloading-immune-system-ema-says#:~:text=European%20Union%20regulators%20warned%20that,to%20the%20European%20Medicines%20Agency\" target=\"_blank\" rel=\"noopener\">Immunerm\u00fcdung durch laufend wiederholtes \u00abBoostern\u00bb gewarnt hatte.<\/a> Die aktuellen Zahlen des BAG zu den Hospitalisierungen nach Impfstatus best\u00e4tigen diese Bef\u00fcrchtung. Bei den \u00fcber 80-j\u00e4hrigen steigen die Hospitalisierungen mit SARS-CoV-2 bei Menschen mit Auffrischimpfung seit Wochen kontinuierlich an und f\u00fchren jetzt mit Abstand am h\u00e4ufigsten zu einer Spitaleinweisung (<a href=\"https:\/\/www.covid19.admin.ch\/de\/vaccination\/status?vaccStatusDevRel=relative\" target=\"_blank\" rel=\"noopener\">letzte Grafik auf dieser BAG-\u00dcbersicht<\/a>).<\/p>\n<h2><strong>Die Pandemie ist l\u00e4ngst vorbei, damit muss auch die befristete Zulassung enden<\/strong><\/h2>\n<p>Man kann es mittlerweile nur noch als kriminell bezeichnen, dass Impfstoffe mit einer befristeten Zulassung (in anderen L\u00e4ndern wird sie treffender Notzulassung genannt) weiterhin angewendet und von offizieller Seite empfohlen werden, obwohl die angeblich gef\u00e4hrliche Lage, die zur befristeten Zulassung gef\u00fchrt hat, l\u00e4ngst nicht mehr vorhanden ist und sich massive Warnsignale aufh\u00e4ufen, dass diese unausgereiften, hastig zugelassenen Impfstoffe zu massiven Nebenwirkungen und sogar Todesf\u00e4llen f\u00fchren.<\/p>\n<p>Wir sehen uns somit in unseren Forderungen an Regierung und Beh\u00f6rden und an die\u00a0<a href=\"https:\/\/www.aletheia-scimed.ch\/de\/schriftwechsel-mit-swissmedic-aletheia-fordert-sofortige-sistierung-der-befristeten-zulassung-der-covid-19-impfstoffe\/\" target=\"_blank\" rel=\"noopener\">Swissmedic<\/a> aus dem Jahre 2021 voll best\u00e4tigt und fordern diese nochmals auf, die\u00a0<strong>besondere Lage und alle Massnahmen sofort zu beenden und die unn\u00f6tigen, unwirksamen und unsicheren \u00abCOVID-Impfstoffe\u00bb sofort aus dem Verkehr zu ziehen.<\/strong>\u00a0Sie erf\u00fcllen nachweislich die Definition einer Impfung nicht, da sie Geimpfte nicht sch\u00fctzen, sondern sichtbar anf\u00e4lliger machen f\u00fcr eine \u00abCOVID-Erkrankung\u00bb und schwere Verl\u00e4ufe.<\/p>\n<p><strong><em>Anmerkung zu unserer Interpretation der Analyse von WIGES:<\/em><\/strong><em>\u00a0Erfahrungen aus unserem \u00c4rzte- und Gesundheitsnetzwerk zeigen, dass selbst bei offensichtlichem Zusammenhang schwerer Nebenwirkungen mit den COVID-19 Impfstoffen h\u00e4ufig keine Meldung erstattet wurde und ein Zusammenhang vorschnell ausgeschlossen wurde. Wir gehen deshalb davon aus, dass Nebenwirkungen bei COVID-19 Impfstoffen seltener gemeldet werden, als dies f\u00fcr Grippeimpfstoffe \u00fcblich war. Wir halten den Vergleich von WIGES zwischen den verschiedenen Impfstoffen als absolut zul\u00e4ssig und die berechneten Faktoren aufgrund dem beobachteten z\u00f6gerlichen Meldeverhalten bei den COVID-19 Impfstoffen als sehr konservativ.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mehr Verdachtsmeldungen mit bleibenden Sch\u00e4den und Todesfolgen Die Initiative Wissenschaft f\u00fcr Gesellschaft\u00a0WIGES\u00a0zeigt in einer f\u00fcr jeden einfach verst\u00e4ndlichen Art auf, dass die Risiken der \u00abCOVID-19 Impfstoffe\u00bb um mindestens zweistellige Faktoren h\u00f6her sind als bisher angenommen und bekannt. Dabei haben Experten die Daten der offiziellen Meldesysteme f\u00fcr Impfnebenwirkungen in Deutschland, Europa, USA, sowie der WHO nach [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,4],"class_list":["post-928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corona","category-impfung"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:17:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/comments?post=928"}],"version-history":[{"count":15,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/928\/revisions"}],"predecessor-version":[{"id":3665,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/posts\/928\/revisions\/3665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media\/1514"}],"wp:attachment":[{"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aletheia-scimed.ch\/de\/wp-json\/wp\/v2\/categories?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}